{"id":11,"date":"2011-02-16T10:27:41","date_gmt":"2011-02-16T09:27:41","guid":{"rendered":"http:\/\/f5len.org\/index.php?entry=entry110216-102741"},"modified":"2015-01-27T15:11:29","modified_gmt":"2015-01-27T14:11:29","slug":"cour-decole","status":"publish","type":"post","link":"http:\/\/f5len.org\/blog\/cour-decole\/","title":{"rendered":"Cour d&rsquo;\u00e9cole"},"content":{"rendered":"<p>A lire <a href=\"http:\/\/f6aoj.ao-journal.com\/crbst_63.html\" target=\"_blank\">le journal de Jeff F6AOJ<\/a> ce matin, on dirait bien qu&rsquo;on l&rsquo;a un peu \u00e9nerv\u00e9 le Jeff. <br \/>En voici un extrait:<br \/><i><b><br \/>Nota : <br \/>Je ne ferai pas comme certains que je ne citerai pas mais \u00e7a me d\u00e9mange s\u00e9rieusement de donner des indicatifs&#8230; C&rsquo;est la derni\u00e8re fois, la prochaine je craquerai&#8230;<br \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"http:\/\/f5len.org\/blog\/pics\/2011\/c_qui_qui.jpg\" alt=\"\" width=\"200\" height=\"199\" \/><br \/>Ils font des pressions sur les op\u00e9rateurs et le disent&#8230;pour corriger le log&#8230; car ils ont l&rsquo;absolue certitude de devoir y \u00eatre.<br \/>On se demande pourquoi, alors qu&rsquo;ils ont d\u00e9j\u00e0 un QSO pour ce pays <br \/>sur cette bande et dans ce mode, cr\u00e9dit\u00e9 au DXCC, et donc qu&rsquo;il n&rsquo;y a m\u00eame pas d&rsquo;enjeu&#8230;<\/b><\/i><\/p>\n<p>Ce n&rsquo;est m\u00eame pas un QSO rarissime quasi impossible \u00e0 refaire, l&rsquo;exp\u00e9dition est encore l\u00e0 pour plusieurs jours, et la bande est facile, refaire le QSO J+1 est sans probl\u00e8me, et bien non, c&rsquo;est pris en tant qu&rsquo;affront personnel insupportable.<\/p>\n<p>C&rsquo;est de la m\u00e9galomanie pure !<\/p>\n<p>Je crains fort que dans peu de temps ce genre d&rsquo;affront ne se r\u00e8gle \u00e0 la descente de l&rsquo;avion de mani\u00e8re hyper violente.<\/p>\n<p>Certains commencent la radio comme cibistes et deviennent Radio-Amateurs, et je les en f\u00e9licite.<\/p>\n<p>R\u00e9cemment j&rsquo;ai d\u00e9couvert que l&rsquo;inverse existe, ce sont ceux qui ayant bani de leur comportement toute r\u00e8gle se retrouvent cibistes, la radio sans r\u00e8gle, m\u00eame s&rsquo;ils ont encore une licence qu&rsquo;ils ne m\u00e9ritent plus.<\/p>\n<p>Le type de cas qui commence ce propos n&rsquo;est pas nouveau, mais prend de l&rsquo;ampleur dans toutes les cat\u00e9gories, C&rsquo;est dans l&rsquo;air du temps, mais ce n&rsquo;est pas une excuse, on commence d&rsquo;une mani\u00e8re ou d&rsquo;une autre, la radio ou autre chose, un hobby, un loisir, et on fini extr\u00e9miste&#8230;<\/p>\n<p>Comme <a href=\"http:\/\/www.ferracci.org\/?p=1424\" target=\"_blank\">d&rsquo;autres<\/a>, je ne peux \u00e9carter l&rsquo;hypoth\u00e8se que ce genre de comportements ne soient qu&rsquo;un effet pervers de la section \u00ab\u00a0leaderboard\u00a0\u00bb de Clublog.<br \/>D&rsquo;autant plus que cette section n&rsquo;apporte rien d&rsquo;int\u00e9ressant au trafic contrairement aux autres options d&rsquo;analyse des logs.<\/p>\n<p>Ou alors, autre hypoth\u00e8se, un afflu aussi inattendu que massif de nouvelles recrues dans le monde amateur. Yes! Que des blondes!<br \/>Bah non m\u00eame pas.<br \/>Ce serait plut\u00f4t des huitres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A lire le journal de Jeff F6AOJ ce matin, on dirait bien qu&rsquo;on l&rsquo;a un peu \u00e9nerv\u00e9 le Jeff. En voici un extrait:Nota : Je ne ferai pas comme certains que je ne citerai pas mais \u00e7a me d\u00e9mange s\u00e9rieusement &hellip; <a href=\"http:\/\/f5len.org\/blog\/cour-decole\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-11","post","type-post","status-publish","format-standard","hentry","category-humeurs"],"_links":{"self":[{"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/posts\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":2,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/posts\/11\/revisions"}],"predecessor-version":[{"id":1050,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/posts\/11\/revisions\/1050"}],"wp:attachment":[{"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/media?parent=11"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/categories?post=11"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/tags?post=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}