{"id":120,"date":"2007-05-24T20:41:25","date_gmt":"2007-05-24T19:41:25","guid":{"rendered":"http:\/\/f5len.org\/index.php?entry=entry070524-214125"},"modified":"2007-05-24T20:41:25","modified_gmt":"2007-05-24T19:41:25","slug":"ondes-courtes","status":"publish","type":"post","link":"http:\/\/f5len.org\/blog\/ondes-courtes\/","title":{"rendered":"Ondes courtes"},"content":{"rendered":"<p>Ce jeudi 24 mai c&#039;est la saint Donatien. Il a fait beau et chaud. Bient\u00f4t l&#039;\u00e9t\u00e9.<br \/>Rien d&#039;extraordinaire.<\/p>\n<p>Ce jeudi, un tr\u00e8s bon ami doit se pr\u00e9parer \u00e0 embarquer dans un a\u00e9roport parisien. Direction Beyrouth. Le Liban. Ensuite, il prendra la direction du sud du pays pour y passer quelques mois  jusqu&#039;\u00e0 l&#039;automne prochain. J&#039;esp\u00e8re que l&#039;\u00e9t\u00e9 sera \u00ab\u00a0doux\u00a0\u00bb&#8230;<\/p>\n<p> <center> <img loading=\"lazy\" decoding=\"async\" src=\"images\/cedre.jpg\" width=\"330\" height=\"215\" border=\"0\" alt=\"\" \/> <\/center> <br \/>Nous savons d\u00e9j\u00e0 que gr\u00e2ce au GSM ou \u00e0 internet nous aurons l&#039;occasion de nous parler r\u00e9guli\u00e8rement. Il installera sa carte Wifi sur son ordinateur portable. S&#039;authentifiera sur le r\u00e9seau informatique de son organisation. Et quelques minutes plus tard, nous pourrons converser via Skype ou MSN comme si il \u00e9tait toujours \u00e0 c\u00f4t\u00e9 de chez moi.<br \/>Rien d&#039;extraordinaire.<\/p>\n<p>Pourtant, ce qui nous ferait vraiment plaisir. C&#039;est de nous retrouver sur ondes courtes. Id\u00e9e quelque peu saugrenue. En tous cas obsol\u00e8te aux yeux de beaucoups.<br \/>Les ondes courtes&#8230; pfff&#8230;<br \/>Pour se faire, il lui aura fallu obtenir une autorisation d&#039;\u00e9mettre du pays h\u00f4te, installer sa station, trouver de la place pour \u00e9riger son antenne. Il lui faudra sans aucun doute, bien plus que quelques minutes. Apr\u00e8s quoi, nous devrons jouer avec la propagation. Trouver la meilleure fr\u00e9quence en fonction de l&#039;heure du jour et de nos disponibilit\u00e9s respectives. Mais, si tout ce passe bien, alors quelques photons qui auront travers\u00e9 la M\u00e9diterran\u00e9e et une bonne partie de l&#039;Europe en une dizaine de millisecondes seront captur\u00e9s par un simple bout de fil sur le toit de ma maison et je pourrai entendre au travers du haut parleur de mon r\u00e9cepteur, les traits et  des points manipul\u00e9s par mon copain. L\u00e0-bas. De l&#039;autre c\u00f4t\u00e9.<br \/>Ca c&#039;est extraordinaire.<br \/>Ca c&#039;est magique.<br \/>Ca a cent ans et c&#039;est tout ce que j&#039;aime.<br \/>Ca s&#039;appelle la radio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce jeudi 24 mai c&#039;est la saint Donatien. Il a fait beau et chaud. Bient\u00f4t l&#039;\u00e9t\u00e9.Rien d&#039;extraordinaire. Ce jeudi, un tr\u00e8s bon ami doit se pr\u00e9parer \u00e0 embarquer dans un a\u00e9roport parisien. Direction Beyrouth. Le Liban. Ensuite, il prendra la &hellip; <a href=\"http:\/\/f5len.org\/blog\/ondes-courtes\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-120","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/posts\/120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/comments?post=120"}],"version-history":[{"count":0,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/posts\/120\/revisions"}],"wp:attachment":[{"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/media?parent=120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/categories?post=120"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/tags?post=120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}