{"id":315,"date":"2012-11-05T23:33:07","date_gmt":"2012-11-05T22:33:07","guid":{"rendered":"http:\/\/f5len.org\/blog\/?p=315"},"modified":"2012-11-05T23:36:52","modified_gmt":"2012-11-05T22:36:52","slug":"memorial-marconi-2012","status":"publish","type":"post","link":"http:\/\/f5len.org\/blog\/memorial-marconi-2012\/","title":{"rendered":"Memorial Marconi 2012"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-316\" title=\"badwx\" src=\"http:\/\/f5len.org\/blog\/wp-content\/uploads\/2012\/11\/badwx.jpg\" alt=\"wx de merde\" width=\"300\" height=\"200\" \/><\/p>\n<p>Respect pour tous ceux qui ont op\u00e9r\u00e9 en portable durant ce week-end pour le Memorial Marconi. Quels temps de merde! Je dois avouer que j&rsquo;ai eu un peu moins de regrets de ne pouvoir participer \u00e0 ce contest depuis la station portable.<br \/>\nJ&rsquo;ai pu n\u00e9anmoins r\u00e9aliser quelques qso depuis la maison avec une simple yagi 5 \u00e9l\u00e9ments fixe vers l&rsquo;ouest samedi en fin d&rsquo;apr\u00e8s-midi. Dans ces conditions, rien de bien extraordinaire \u00e0 signaler d&rsquo;autant plus que la propagation n&rsquo;\u00e9tait vraiment pas g\u00e9niale. Une douzaine de qso seulement.<br \/>\nJ&rsquo;ai pu n\u00e9anmoins qso F6ETI\/p en JN15 op\u00e9r\u00e9e par l&rsquo;ami Bernard F5DE avec de bons signaux. La machine \u00e0 r\u00e9parer la propag fonctionne parfaitement \ud83d\ude09<br \/>\nJ&rsquo;en ai profit\u00e9 pour faire quelques manip avec Spectrum lab sur les signaux en provenance de F6ETI en AS (Aircraft Scatter). On obtient facilement une augmentation de de 15 dB (CAG off) et qui durent de 15 \u00e0 20s.<br \/>\nOn en reparlera.<\/p>\n<p>[tweetandlike_buttons]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Respect pour tous ceux qui ont op\u00e9r\u00e9 en portable durant ce week-end pour le Memorial Marconi. Quels temps de merde! Je dois avouer que j&rsquo;ai eu un peu moins de regrets de ne pouvoir participer \u00e0 ce contest depuis la &hellip; <a href=\"http:\/\/f5len.org\/blog\/memorial-marconi-2012\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[21,20],"class_list":["post-315","post","type-post","status-publish","format-standard","hentry","category-contests","tag-contest-vhf","tag-marconi-2012"],"_links":{"self":[{"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/posts\/315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/comments?post=315"}],"version-history":[{"count":5,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/posts\/315\/revisions"}],"predecessor-version":[{"id":321,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/posts\/315\/revisions\/321"}],"wp:attachment":[{"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/media?parent=315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/categories?post=315"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/tags?post=315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}