{"id":57,"date":"2008-11-07T15:39:58","date_gmt":"2008-11-07T14:39:58","guid":{"rendered":"http:\/\/f5len.org\/index.php?entry=entry081107-153958"},"modified":"2015-09-16T12:06:33","modified_gmt":"2015-09-16T10:06:33","slug":"participation-aux-contests-vhf","status":"publish","type":"post","link":"http:\/\/f5len.org\/blog\/participation-aux-contests-vhf\/","title":{"rendered":"Participation aux contests VHF"},"content":{"rendered":"<p>On dit et on lit un peu partout que la participation aux concours VHF est en baisse depuis ces derni\u00e8res ann\u00e9es. Ce mal, si il est av\u00e9r\u00e9, est-il un mal fran\u00e7ais ou plus g\u00e9n\u00e9ralement une tendance de fond dans toute l&rsquo;Europe?<br \/>\nJ&rsquo;ai donc repris les r\u00e9sultats des dix derni\u00e8res ann\u00e9es (de 1997 \u00e0 2007) de deux contests majeurs en VHF:<br \/>\n&#8211; IARU R1 VHF contest<br \/>\n&#8211; Memorial Marconi CW contest.<br \/>\nLe second comme son nom l&rsquo;indique \u00e9tant exclusivement en CW.<br \/>\nJ&rsquo;ai extrait des r\u00e9sultats europ\u00e9ens les donn\u00e9es suivantes:<br \/>\n&#8211; le nombre de participants fran\u00e7ais en mono-op<br \/>\n&#8211; le nombre de participants fran\u00e7ais en multi-op<br \/>\n&#8211; le nombre de participants europ\u00e9ens en mono-op<br \/>\n&#8211; le nombre de participants europ\u00e9ens en multi-op<\/p>\n<p>&#8211; le nombre de qso r\u00e9alis\u00e9 par le 1er fran\u00e7ais en mono-op<br \/>\n&#8211; le nombre de qso r\u00e9alis\u00e9 par les 1er fran\u00e7ais en multi-op<br \/>\n&#8211; le nombre de qso r\u00e9alis\u00e9 par le 1er europ\u00e9en en mono-op<br \/>\n&#8211; le nombre de qso r\u00e9alis\u00e9 par les 1er europ\u00e9ens en multi-op<\/p>\n<p>Attention, les participants sont les stations ayant effectivement envoy\u00e9 un log et qui apparaissent dans les classements.<br \/>\nCa semble beaucoup mais sur un graphique ca reste raisonnable.<br \/>\nVoyons de ce que tout cela donne maintenant.<\/p>\n<p><b>IARU VHF &#8211; participation:<\/b><br \/>\n(Cliquez pour agrandir l&rsquo;image)<br \/>\n<img loading=\"lazy\" decoding=\"async\" id=\"img_float_left\" class=\"alignnone\" src=\"http:\/\/f5len.org\/blog\/pics\/2008\/om_iaruvhf.jpg\" alt=\"\" width=\"512\" height=\"312\" border=\"0\" \/><br \/>\nContrairement \u00e0 ce que je pensais le nombre de participants F mono-op\u00e9rateur est en l\u00e9g\u00e8re augmentation depuis 2003. La canicule de 2003 n&rsquo;a donc eu aucun effet sur les OMs F \ud83d\ude09 tout comme l&rsquo;ouverture aux bande HF aux OMs F1\/F4 intervenu en 2004 ce qui est une id\u00e9e g\u00e9n\u00e9ralement admise. Le trafic contest n&rsquo;est donc pas le reflet exact du trafic quotidien qui lui a semble-t-il d\u00e9cru significativement depuis cette date. Cette tendance est globalement identique en F que dans le reste de l&rsquo;Europe.<br \/>\nA l&rsquo;inverse, les \u00e9quipes multi-op\u00e9rateurs semblent ne pas avoir le vent en poupe et ceci depuis au moins la fin des ann\u00e9es 90 tant au niveau fran\u00e7ais que europ\u00e9en.<\/p>\n<p><b>IARU VHF &#8211; nombre de qso r\u00e9alis\u00e9s:<\/b><br \/>\n(Cliquez pour agrandir l&rsquo;image)<br \/>\n<a><img loading=\"lazy\" decoding=\"async\" id=\"img_float_left\" src=\"http:\/\/f5len.org\/blog\/pics\/2008\/q_iaruvhf.jpg\" alt=\"\" width=\"512\" height=\"266\" border=\"0\" \/><\/a><br \/>\nSur ce graphique les tendances sont plus difficiles \u00e0 mettre en \u00e9vidence. Pour les stations multi-op fran\u00e7aises il semble cependant que le nombre max de qso soit en d\u00e9croissance constante depuis 10 ans. Si les stations multi-ops F ont plus de mal a r\u00e9aliser un grand nombre de qso alors que la courbe europ\u00e9enne reste globalement stable indique soit des stations moins performantes, soit un d\u00e9placement de l&rsquo;activit\u00e9 dans des zones plus \u00e9loign\u00e9es de la France. Soit les deux&#8230;<br \/>\nPour les mono-op le nombre maximal de qso atteints est globalement constant except\u00e9 en 1997 2003 et 2007. Ces pointes sont dues \u00e0 la participation d&rsquo;une station pour le moins performante dans cette cat\u00e9gorie (F6HPP). Au-del\u00e0 des qualit\u00e9 de l&rsquo;op\u00e9rateur ces pointes confirment que 10W dans une 9el sur un manche \u00e0 ballais ne permettent pas d&rsquo;obtenir des performances ad\u00e9quates&#8230;<\/p>\n<p><b>Memorial Marconi &#8211; Participation:<\/b><br \/>\n(Cliquez pour agrandir l&rsquo;image)<br \/>\n<a><img loading=\"lazy\" decoding=\"async\" id=\"img_float_left\" src=\"http:\/\/f5len.org\/blog\/pics\/2008\/om_marconi.jpg\" alt=\"\" width=\"512\" height=\"307\" border=\"0\" \/><\/a><br \/>\nLa m\u00eame tendance de d\u00e9clin du nombre de stations multi-op au niveau F et Eu se dessine. Elle semble m\u00eame s&rsquo;acc\u00e9l\u00e9rer ses deux derni\u00e8res ann\u00e9es. En France, le nombre de d\u00e9part \u00e9tant tr\u00e8s faible (6), la variation reste faible voir nulle.<br \/>\nAu niveau mono-op la tendance est \u00e0 l&rsquo;augmentation en Europe alors qu&rsquo;en France c&rsquo;est l&rsquo;inverse. A confirmer en 2008(&#8230;).<\/p>\n<p><b>Memorial Marconi &#8211; nombre de qso r\u00e9alis\u00e9s:<\/b><br \/>\n(Cliquez pour agrandir l&rsquo;image)<br \/>\n<a><img loading=\"lazy\" decoding=\"async\" id=\"img_float_left\" src=\"http:\/\/f5len.org\/blog\/pics\/2008\/q_marconi.jpg\" alt=\"\" width=\"512\" height=\"270\" border=\"0\" \/><\/a><br \/>\nDans les deux cat\u00e9gories les premiers augmentent r\u00e9guli\u00e8rement leur nombre de qso ce qui est l&rsquo;inverse de l&rsquo;IARU VHF. Il peut subsister des accidents de parcours mais la croissance est constante depuis 1998. Malgr\u00e9 la suppression de l&rsquo;examen cw dans la plus part des pays europ\u00e9ens ce contest semble rassembler encore nombre de fid\u00e8les motiv\u00e9s. Motiv\u00e9s car faire du portable au mois de novembre, il faut l&rsquo;\u00eatre!<br \/>\n<b>Conclusion :<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" id=\"img_float_right\" src=\"http:\/\/f5len.org\/blog\/pics\/2008\/equipe.jpg\" alt=\"\" width=\"150\" height=\"112\" border=\"0\" \/>L&rsquo;activit\u00e9 globale ne me semble pas si catastrophique qu&rsquo;on veut bien le dire. Cependant, je suis persuad\u00e9 que ces courbes cachent de grandes disparit\u00e9s r\u00e9gionales.<br \/>\nEn France, le sud ouest est sans doute fort d\u00e9savantag\u00e9 par l&rsquo;\u00e9loignement du centre de l&rsquo;activit\u00e9 THF (DL\/OK). L&rsquo;ouest de la France doit \u00e9galement souffrir de la d\u00e9saffection des OMs anglais. O\u00f9 sont pass\u00e9s les G8P, M1A et autre M1CRO?<br \/>\nOn peut trouver rassurant que l&rsquo;ouverture aux bandes HF des amis F1\/F4 ne les ait pas totalement d\u00e9tourn\u00e9 de leur activit\u00e9s VHF. Une fois que l&rsquo;on a contact\u00e9 une brouette de W et une pellet\u00e9 de JA on a aussi fait le tour non? \ud83d\ude09 Ce ph\u00e9nom\u00e8ne peut avoir \u00e9t\u00e9 n\u00e9anmoins compens\u00e9 par l&rsquo;arriv\u00e9e massive de quelques stations F0 particuli\u00e8rement motiv\u00e9es \u00e0 participer aux contests. Ce qui est en soit une bonne chose, cette activit\u00e9 permettant d&rsquo;apprendre beaucoup de choses, surtout quand on la partage en \u00e9quipe.<br \/>\nIl est \u00e9tonnant alors de voir le nombre d&rsquo;oms participants augmenter alors que le nombre de qso r\u00e9alis\u00e9s semble suivre une courbe inverse. Je m&rsquo;interroge.<br \/>\nLe niveau d&rsquo;\u00e9quipement serait-il suffisant?&#8230;<br \/>\nJe suis surpris du nombre d&rsquo;oms trafiquant avec une antenne verticale ou une 4el sous les tuiles. Alors! On ose plus monter d&rsquo;antennes?<br \/>\nPlus ennuyeux est, \u00e0 mon sens, la baisse continue du nombre d&rsquo;\u00e9quipes.<br \/>\nCeci peut expliquer, aussi en partie, l&rsquo;augmentation du nombre d&rsquo;OMs participants individuellement par un effet de vase communiquant. Pourtant on ne peut qu&rsquo;encourager les passionn\u00e9s \u00e0 se regrouper pour mettre en route des stations performantes.<br \/>\nC&rsquo;est bien plus ais\u00e9 et beaucoup plus sympa \u00e0 plusieurs.<\/p>\n<p>Cu on the air!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>On dit et on lit un peu partout que la participation aux concours VHF est en baisse depuis ces derni\u00e8res ann\u00e9es. Ce mal, si il est av\u00e9r\u00e9, est-il un mal fran\u00e7ais ou plus g\u00e9n\u00e9ralement une tendance de fond dans toute &hellip; <a href=\"http:\/\/f5len.org\/blog\/participation-aux-contests-vhf\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-57","post","type-post","status-publish","format-standard","hentry","category-contests"],"_links":{"self":[{"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/posts\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/comments?post=57"}],"version-history":[{"count":2,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/posts\/57\/revisions"}],"predecessor-version":[{"id":1060,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/posts\/57\/revisions\/1060"}],"wp:attachment":[{"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/media?parent=57"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/categories?post=57"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/tags?post=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}