{"id":22,"count":7,"description":"","link":"https:\/\/f5len.org\/blog\/tag\/tropo\/","name":"Tropo","slug":"tropo","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/tags\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/f5len.org\/blog\/wp-json\/wp\/v2\/posts?tags=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}